{"id":2599,"date":"2018-10-31T23:16:43","date_gmt":"2018-11-01T05:16:43","guid":{"rendered":"http:\/\/latinamericanliteraturetoday.wp\/2018\/10\/sergio-ramirez-morethandeserving-cervantes-jose-juan-colin\/"},"modified":"2023-06-06T08:59:58","modified_gmt":"2023-06-06T14:59:58","slug":"sergio-ramirez-morethandeserving-cervantes-jose-juan-colin","status":"publish","type":"post","link":"https:\/\/latinamericanliteraturetoday.org\/es\/2018\/10\/sergio-ramirez-morethandeserving-cervantes-jose-juan-colin\/","title":{"rendered":"&#8220;Sergio Ram\u00edrez, el Cervantes m\u00e1s que merecido&#8221; de Jos\u00e9 Juan Col\u00edn"},"content":{"rendered":"<div><\/div>\n<div class=\"caption\"><\/div>\n<style type=\"text\/css\">p.p1 {margin: 0.0px 0.0px 0.0px 0.0px; line-height: 23.0px; font: 12.0px 'Times New Roman'}<br \/>p.p2 {margin: 0.0px 0.0px 0.0px 0.0px; line-height: 23.0px; font: 12.0px 'Times New Roman'; min-height: 15.0px}<br \/>span.Apple-tab-span {white-space:pre}<br \/><\/style>\n<p>El pasado noviembre la literatura centroamericana, en especial la nicarag\u00fcense, recibi\u00f3 un enorme espaldarazo ya que, como se sabe, Sergio Ram\u00edrez fue designado como Premio Cervantes 2017. El hecho no es menor, ya que a lo largo de la historia la regi\u00f3n del Istmo ha aparecido espor\u00e1dicamente en el imaginario continental y en las m\u00e1s de las veces debido a las dictaduras militares, represi\u00f3n gubernamental, inestabilidad pol\u00edtica, crimen organizado y\/o violencia com\u00fan. En el rubro de la literatura desde que el vate nicarag\u00fcense Rub\u00e9n Dar\u00edo hiciera aparecer a la regi\u00f3n en el mapa mundial a la vuelta de los siglos XIX-XX, o cuando no hayan sido los logros del Novel guatemalteco Miguel \u00c1ngel Asturias tiempo despu\u00e9s, de la literatura de la regi\u00f3n se conoc\u00eda muy poco. Sin embargo, escritores de estas generaciones sentaron las bases para que luego otros siguieran picando piedra y poco a poco, sin menosprecio de los cr\u00edticos que han puesto su granito de arena para que la literatura del istmo se conozca en otras latitudes, se hicieran reconocibles entre los entendidos (y los no tanto) nombres como el mismo Asturias, Augusto Monterroso, Claribel Alegr\u00eda, Roque Dalton, Ernesto Cardenal, Gioconda Belli y un largo etc. Luego generaciones m\u00e1s recientes que se vienen desarrollando con m\u00e1s soltura promovidas en parte por \u201cCentroam\u00e9rica cuenta\u201d, reuni\u00f3n anual de escritores que se lleva a cabo en Nicaragua (con repetidora en La Feria de Guadalajara), creada y presidida por el mismo Sergio Ram\u00edrez, tienen en su haber ya un buen n\u00famero de obras, muchas de ellas traducidas a diferentes idiomas: Horacio Castellanos Moya, Jacinta Escudos, Rodrigo Rey Rosa entre otros. De manera que hoy d\u00eda, si bien la literatura centroamericana no ostenta el escaparate de la mexicana o la argentina, si podemos afirmar que poco a poco se asoma al universo literario y es cada vez m\u00e1s frecuente encontrarnos con buenas noticias en torno a esta parte de Am\u00e9rica; el Premio Cervantes, por ejemplo.<\/p>\n<p>La obra de Sergio Ram\u00edrez es muy amplia y los estudios sobre la misma son ampl\u00edsimos. Es un escritor que se ha acercado al desarrollo de su obra sin menoscabo de ning\u00fan g\u00e9nero (la poes\u00eda no se me da muy bien, contar\u00eda en alguna ocasi\u00f3n, por eso no la frecuento) incluyendo historias infantiles. Pero para el que esto escribe Sergio es un contador de historias nato. Me lo puedo imaginar muy bien en los albores de la literatura: la comunicaci\u00f3n oral, con sus oyentes sentados en derredor de un fuego al caer la tarde y \u00e9l inventando historias para entretener a su audiencia, porque adem\u00e1s es un gran conversador. As\u00ed se leen sus primeros cuentos publicados en 1963 en un volumen de t\u00edtulo sencillo, <i>Cuentos<\/i>, mezcla de autobiograf\u00eda y ficci\u00f3n, donde se advierte la simpleza, frescura e imaginaci\u00f3n de los primeros esbozos del escritor en ciernes. Posteriormente, en su primer texto de largo aliento, <i>Tiempo de fulgor<\/i> (1970) muestra que las ense\u00f1anzas de los maestros del <i>boom<\/i> hab\u00edan ca\u00eddo en tierra f\u00e9rtil y se lee el mon\u00f3logo interior, el soliloquio, el di\u00e1logo, la narraci\u00f3n omnisciente, la creaci\u00f3n de mitos; esta es una novela que acusa sin duda la influencia estil\u00edstica de la \u00e9poca. Pero esos tiempos eran tambi\u00e9n de conflictos pol\u00edticos, as\u00ed que en <i>De tropeles y tropel\u00edas<\/i> (1972) parodia en una serie de textos cortos y vi\u00f1etas acompa\u00f1adas por sendas l\u00e1minas del artista alem\u00e1n Dieter Masuhr a un personaje persistente y diab\u00f3lico en Am\u00e9rica Latina, el dictador. El carnaval, la f\u00e1bula, lo grotesco dan vida a este personaje cuya imagen evoca a la dinast\u00eda Somoza (dictadores de Nicaragua en esos a\u00f1os) en tanto se publica durante el periodo revolucionario.<\/p>\n<p>Luego en <i>Charles Atlas tambi\u00e9n muere<\/i> (1976) el escritor se aventura un tanto m\u00e1s en la cuesti\u00f3n de estilo y exploraci\u00f3n de la t\u00e9cnica. Aunado a ello, el acudir cada vez m\u00e1s frecuentemente a la imaginaci\u00f3n en la formaci\u00f3n de sus historias viene a desembocar en <i>\u00bfTe dio miedo la sangre?<\/i> (1977), que es una mir\u00edada de historias contadas a la vez que corren mayormente paralelas unas a otras, aunque entrever\u00e1ndose de vez en vez para establecer una mirada generalizada de la efervescente sociedad revolucionaria. Con <i>Castigo divino<\/i> (1988) inaugura su entrada a novela policiaca, g\u00e9nero que, como se ver\u00e1 m\u00e1s adelante en <i>El cielo llora por m\u00ed<\/i> (2008) y <i>Ya nadie llora por m\u00ed<\/i> (2017), continuar\u00eda explotando. Fue incluso Premio Dashiell Hammett en 1990. La novela centra su argumento en el personaje Oliverio Casta\u00f1eda, asesino en serie que debe ser detenido ya que ha envenenado a varias mujeres y el n\u00facleo es la investigaci\u00f3n del caso y su resoluci\u00f3n.<\/p>\n<p>Ram\u00edrez vuelve despu\u00e9s, nunca lo ha abandonado, al g\u00e9nero de sus inicios, la narrativa corta. <i>Clave de sol<\/i> (1992) es una serie de cuentos en la que el protagonista es Nicaragua concebida desde diferentes perspectivas y de manera interna. La verosimilitud de la protagonista, si queremos que sea Nicaragua, se establece en la medida que de la lectura de los relatos emanan el color y el calor necesarios para sentir que se observa al pa\u00eds desde adentro. Quiz\u00e1 la salvedad sea \u201cHeiliger Nikolaus\u201d que tiene como escenario una ciudad alemana en un d\u00eda de Navidad; incluso se dir\u00eda que se encuentra fuera de lugar, quiz\u00e1 sea m\u00e1s bien un respiro, un par\u00e9ntesis, un momento de distracci\u00f3n en la cotidianidad nicarag\u00fcense. Hay una novela que nos parece singular, <i>Un baile de m\u00e1scaras<\/i> (1995), en el sentido de que fiel a la exploraci\u00f3n y la evoluci\u00f3n de su escritura, Ram\u00edrez crea una novela cuya acci\u00f3n transcurre en un solo d\u00eda: 5 de agosto de 1942, que es la fecha del nacimiento del autor. Esta novela es una suerte de recorrido universal de aconteceres de un solo d\u00eda en la historia de la humanidad comparada con ese mismo d\u00eda en Masatepe, su pueblo natal. Es una historia de familia, nost\u00e1lgica a final de cuentas. Y manteni\u00e9ndose en la memoria como origen esencial de su producci\u00f3n, publica luego una novela de corte hist\u00f3rico, <i>Margarita est\u00e1 linda la mar<\/i> (1998), ganadora del primer Premio Alfaguara, donde se cuenta la historia del regreso de Rub\u00e9n Dar\u00edo a Nicaragua a principios del siglo XX convertido ya en el vate que hab\u00eda revolucionado la poes\u00eda y le adjudicaba brillo especial al Modernismo. Dar\u00edo regresa para morir en su pa\u00eds natal y se quiere que su cerebro sea objeto de estudio, para as\u00ed entender por qu\u00e9 Dar\u00edo es Dar\u00edo. Pero luego el absurdo lo torna en objeto, nada m\u00e1s. Pero la historia queda ah\u00ed para que no caiga en el olvido.<\/p>\n<p>La \u00faltima revoluci\u00f3n de Am\u00e9rica Latina en el siglo XX, la Sandinista, es una constante en la literatura del galardonado, \u201cen la literatura de Centroam\u00e9rica se escuchan siempre detr\u00e1s los disparos de la guerra\u201d, palabras m\u00e1s palabras menos, dir\u00eda alguna vez Ram\u00edrez. Por ello, movido por una suerte de ajuste de cuentas con la historia y la cr\u00edtica postconflicto escribe un libro de memorias, <i>Adi\u00f3s muchachos<\/i> (1999), con un subt\u00edtulo que reza \u201cMemoria de la Revoluci\u00f3n Sandinista\u201d. En este libro Ram\u00edrez cuenta el episodio de la revoluci\u00f3n \u201cComo yo la viv\u00ed, no como me contaron que fue\u201d, de manera que leemos la interpretaci\u00f3n intimista de lo que fueron los hechos; con una caravana a la participaci\u00f3n femenina. Una perspectiva similar se advierte en <i>Catalina y Catalina<\/i> (2001), colecci\u00f3n de cuentos que acusan ya un dominio de los espacios narrativos y la verosimilitud impuesta a las historias las compagina con la memoria de la revoluci\u00f3n. La pluralidad tem\u00e1tica y la universalidad separa un tanto esta colecci\u00f3n de las anteriores, pero las tradiciones de su patria no quedan relegadas a un segundo t\u00e9rmino, por el contrario, desde el primer cuento queda claro el proceso y valor de las costumbres en la sociedad nicarag\u00fcense.<\/p>\n<p>La tradici\u00f3n de la novela de la dictadura en Am\u00e9rica Latina tiene ya un espacio ganado a pulso en el canon literario y <i>Sombras nada m\u00e1s<\/i> (2002) es prueba de que Ram\u00edrez no se sustrajo a ello, mucho menos habiendo sido participante activo en el proceso revolucionario de Nicaragua. Esta novela, no obstante, no es s\u00f3lo una novela m\u00e1s con este tema, aqu\u00ed sobresale la complejidad narrativa para abordar la tem\u00e1tica del dictador poniendo al personaje en segundo plano y trat\u00e1ndolo de manera tangencial, al estilo de La Nueva Novela Hist\u00f3rica.\u00a0 Y el mismo estilo se utiliza en <i>Mil y una muertes <\/i>(2005) cuando el narrador, Sergio Ram\u00edrez, siendo vicepresidente de Nicaragua seg\u00fan cuenta la novela, en un viaje a Polonia se encuentra con las fotograf\u00edas tomadas por el fot\u00f3grafo nicarag\u00fcense, Castell\u00f3n. Los cap\u00edtulos se alternar\u00e1n en su narraci\u00f3n siempre en primera persona, siendo el otro narrador el mismo Castell\u00f3n. El tema de la novela ser\u00e1 el intento por (re)crear la posible existencia del fot\u00f3grafo en base a informaci\u00f3n encontrada por Ram\u00edrez y la experiencia del mismo Castell\u00f3n.<\/p>\n<p>Un libro diferente es <i>El reino animal<\/i> (2007), cuya colecci\u00f3n de relatos rompe completamente con la tradici\u00f3n que el mismo Ram\u00edrez impuso a sus cuentos. Es una suerte de experimentaci\u00f3n, un bestiario que, si bien es cierto atrae justamente por su diferencia, tambi\u00e9n valga decir que el que esto escribe hubiera deseado la continuidad de un estilo ya bien definido y un oficio bien labrado. Por cierto, conviene se\u00f1alar que quiz\u00e1 el mismo Ram\u00edrez lo not\u00f3 y en su siguiente colecci\u00f3n <i>Flores oscuras<\/i> (2013), vuelve por sus fueros y nos entrega 12 cuentos donde muestra el pleno control de la narraci\u00f3n corta. Ram\u00edrez se mueve como pez en el agua en el g\u00e9nero y rescata detalles nimios de la sociedad para convertirlos en historias trascendentales. Va desde la autobiograf\u00eda hasta eventos sin mayor importancia, como la charla con un desconocido en una ciudad italiana.<\/p>\n<p><i>El cielo llora por m\u00ed<\/i> (2008) es una novela policiaca, cuyo escenario es la Nicaragua de postguerra y el personaje central, el detective, posee un nombre por dem\u00e1s revelador, Dolores Morales. Como ya se dijo, esta es una novela policial cl\u00e1sica con un muerto,\u00a0 pocos disparos, un detective (venido a menos) y un caso por resolver que es finalmente resuelto. Antes con <i>Castigo divino<\/i> Ram\u00edrez se hab\u00eda aventurado en el g\u00e9nero pero no lo cultiv\u00f3 a la manera de las grandes sagas de Padura Fuentes, Taibo II, o D\u00edaz Eterovich por ejemplo. Sin embargo la \u00faltima novela de Ram\u00edrez, <i>Ya nadie llora por m\u00ed<\/i> (2017), va apuntando en esa direcci\u00f3n en tanto que \u00e9sta va protagonizada por los mismos personajes con un final abierto, cuya estrategia indica que habr\u00e1, por lo menos, una tercer novela en torno al inspector Dolores Morales.<\/p>\n<p>En su pen\u00faltima novela <i>Sara<\/i> (2015), Ram\u00edrez reescribe la historia de Sara y Abraham, pero esta vez desde la perspectiva de ella. El n\u00facleo de la novela est\u00e1 sustentado por la relaci\u00f3n tensa de Sara con el Mago, enti\u00e9ndase Dios, y por la fuerza del personaje en tanto mujer. Sara cuestiona los designios del Mago y en la novela se desarrolla como un personaje muy por encima de las expectativas y personalidad que se lee en la Historia Sagrada.<\/p>\n<p>Por otra parte, la producci\u00f3n narrativa de Sergio Ram\u00edrez no se detiene en la ficci\u00f3n y las memorias, sino que va m\u00e1s all\u00e1 y entrecaladas con las publicaciones de novelas y colecciones de cuentos existe un gran numero de colecciones de ensayos, ensayos sueltos, antolog\u00edas, pr\u00f3logos, conferencias, prosa profana, art\u00edculos y notas de opini\u00f3n en diversas publicaciones: <i>La jornada<\/i> y <i>El pa\u00eds<\/i>, entre muchos otros. La tem\u00e1tica de los ensayos y notas cubre todos los \u00e1ngulos en el desarrollo de las sociedades: literatura, pol\u00edtica, formas de gobierno, cultura popular, etc. El espacio prestado para esta nota es insuficiente para detallar toda su obra de manera que, sin af\u00e1n de ser exhaustivo, s\u00f3lo titular\u00e9 lo m\u00e1s sobresaliente: <i>Antolog\u00eda del cuento centroamericano <\/i>(1973)<i>; Puertos abiertos, Antolog\u00eda del cuento centroamericano <\/i>(2011); <i>Puertas abiertas, antolog\u00eda de poes\u00eda centroamericana <\/i>(2011)<i>; Un espejo roto, antolog\u00eda del nuevo cuento de Centroam\u00e9rica y Rep\u00fablica Dominicana <\/i>(2014)<i>; <\/i> Ensayo: <i>El pensamiento vivo de Sandino<\/i>, <i>Seguimos de frente, Julio, est\u00e1s en Nicaragua, El alba de oro, Las armas del futuro, Balcanes y volcanes, Oficios compartidos, Mentiras verdaderas, El viejo arte de mentir, Se\u00f1or de los tristes, Tambor olvidado, La manzana de oro<\/i> y, como ya se anticip\u00f3, un largo etc.<\/p>\n<p>Termino con una nota personal. Conoc\u00ed a Sergio Ram\u00edrez en 1994 (\u00bfo ser\u00eda 95?) cuando en la Universidad de Nuevo M\u00e9xico le\u00ed por primera vez su cuento, \u201cEl estudiante\u201d, que se haya en un volumen titulado <i>Cuentos<\/i>, el cual fue parte de una serie especial publicada por la UNAM sobre narrativa corta. Las estrellas se alinearon entonces y ca\u00ed luego a la cuenta de que Sergio y su obra ser\u00edan parte importante en mi carrera, ya que yo a\u00fan estudiaba mi licenciatura. Uno o dos a\u00f1os despu\u00e9s tuve la fortuna de que Sergio hac\u00eda campa\u00f1a pol\u00edtica con miras a la presidencia de Nicaragua y visit\u00f3 la Universidad de Nuevo M\u00e9xico, donde finalmente le conoc\u00ed en persona. Sobra decir que el encuentro ratific\u00f3 el hecho de que las estrellas segu\u00edan alineadas a mi favor. Ah\u00ed descubr\u00ed que el exrevolucionario, y luego exvicepresidente de Nicaragua despu\u00e9s del triunfo de la Revoluci\u00f3n Sandinista y candidato a la presidencia, adem\u00e1s de ser muy alto (parec\u00eda jugador de baloncesto) era generoso, sencillo, de risa franca, que no escatim\u00f3 su tiempo para conversar un poco con aqu\u00e9l estudiante que aspiraba entonces a una maestr\u00eda en espa\u00f1ol; en fin, descubr\u00ed que Sergio era lo que se conoce como \u201cun gran tipo\u201d.<\/p>\n<p>Pues bien, el pasado jueves 16 de noviembre de 2017 el jurado del premio Cervantes eligi\u00f3 por unanimidad a Sergio Ram\u00edrez como ganador del premio, que es quiz\u00e1 el de m\u00e1s prestigio en lengua espa\u00f1ola. Me embarg\u00f3 de inmediato un pensamiento feliz cuando me enter\u00e9 del hecho y record\u00e9 al momento las muchas ocasiones en que he tenido el privilegio de conversar con \u00e9l: Maryland, Guatemala, Managua, Oklahoma, Guadalajara, Arkansas, etc. siempre persigui\u00e9ndole, en tanto que su obra ha sido uno de mis principales objetos de estudio y \u00e9l, reitero, due\u00f1o de una generosidad inagotable. Total, reafirm\u00e9 la convicci\u00f3n de que por el lado que se le mire, es un premio m\u00e1s que merecido.<\/p>\n<p style=\"text-align: right;\">Jos\u00e9 Juan Col\u00edn<br \/>\nUniversidad de Oklahoma<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado noviembre la literatura centroamericana, en especial la nicarag\u00fcense, recibi\u00f3 un enorme espaldarazo ya que, como se sabe, Sergio Ram\u00edrez fue designado como Premio Cervantes 2017. El hecho no es menor, ya que a lo largo de la historia la regi\u00f3n del Istmo ha aparecido espor\u00e1dicamente en el imaginario continental y en las m\u00e1s de las veces debido a las dictaduras militares, represi\u00f3n gubernamental, inestabilidad pol\u00edtica, crimen organizado y\/o violencia com\u00fan. En el rubro de la literatura desde que el vate nicarag\u00fcense Rub\u00e9n Dar\u00edo hiciera aparecer a la regi\u00f3n en el mapa mundial a la vuelta de los siglos XIX-XX, o cuando no hayan sido los logros del Novel guatemalteco Miguel \u00c1ngel Asturias tiempo despu\u00e9s, de la literatura de la regi\u00f3n se conoc\u00eda muy poco.<\/p>\n","protected":false},"author":3,"featured_media":2596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5734],"tags":[38,4457],"genre":[2019],"pretext":[2033,2032],"section":[2395],"translator":[2458],"lal_author":[3594],"class_list":["post-2599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-nicaragua","tag-numero-8","genre-essay-es","pretext-ensayo-es","pretext-essay-es","section-featured-author-sergio-ramirez-es","translator-arthur-malcolm-dixon-es","lal_author-jose-juan-colin-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts\/2599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/comments?post=2599"}],"version-history":[{"count":0,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts\/2599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/media\/2596"}],"wp:attachment":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/media?parent=2599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/categories?post=2599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/tags?post=2599"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/genre?post=2599"},{"taxonomy":"pretext","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/pretext?post=2599"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/section?post=2599"},{"taxonomy":"translator","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/translator?post=2599"},{"taxonomy":"lal_author","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/lal_author?post=2599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}