{"id":2338,"date":"2018-07-23T23:25:56","date_gmt":"2018-07-24T05:25:56","guid":{"rendered":"http:\/\/latinamericanliteraturetoday.wp\/2018\/07\/six-poems-nestor-mendoza\/"},"modified":"2023-06-06T09:41:12","modified_gmt":"2023-06-06T15:41:12","slug":"six-poems-nestor-mendoza","status":"publish","type":"post","link":"https:\/\/latinamericanliteraturetoday.org\/es\/2018\/07\/six-poems-nestor-mendoza\/","title":{"rendered":"Seis poemas de N\u00e9stor Mendoza"},"content":{"rendered":"<div><\/div>\n<div class=\"caption\"><\/div>\n<p><strong>PESCADO<\/strong><\/p>\n<p>Detr\u00e1s de la cabeza y los ojos<br \/>\na\u00fan queda un poco de carne.<\/p>\n<p>Si tuvieras tiempo suficiente<br \/>\nentre cada bocado<br \/>\nhar\u00edas un conteo de las espinas,<br \/>\nde las escamas que olvidaste desencajar.<\/p>\n<p>Debes comer, no dejar sobras.<br \/>\nImagina que el pez nad\u00f3 hasta tu plato<br \/>\nolvidando su hogar debajo de las olas.<br \/>\nImagina que se deshizo del sol,<br \/>\nde las algas,<br \/>\nque ya no va a desovar.<br \/>\nAlimenta tu carne con nueva carne.<br \/>\nEl pescado est\u00e1 frito.<br \/>\nNo temas.<br \/>\nSi no sangra no hay pecado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ANDAMIOS<\/strong><\/p>\n<p>Los andamios elevan y sujetan.<br \/>\nTu vida depende de su eficacia,<br \/>\nde que conserven la solidez<br \/>\ndel equilibrio de los cables.<\/p>\n<p>Te entregas al oficio de sostener<br \/>\nel cuerpo de quien trabaja en la altura.<\/p>\n<p>Advierto tu silueta que se muestra<br \/>\nen el andamio.<br \/>\nY la mano que se ajusta a la vida<br \/>\ny depende s\u00f3lo de las tablas firmes<br \/>\nque impiden la ca\u00edda.<\/p>\n<p>Eres el equilibrista;<br \/>\nquien limpia las ventanas, quien pinta,<br \/>\nquien coloca los ladrillos.<br \/>\nCrees ser el due\u00f1o de la elevaci\u00f3n<br \/>\ny de la brisa de las palomas.<\/p>\n<p>Dios es pura altura, dices, y dejas de temerle.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DESCOMPOSICI\u00d3N<\/strong><\/p>\n<p>La guayaba se pudre<br \/>\nde adentro<br \/>\nhacia afuera.<\/p>\n<p>No quiere desprenderse<br \/>\nde las ramas aunque<br \/>\nsu cuerpo sienta<br \/>\nque la tierra hala<br \/>\nsu jugo,<br \/>\nque llama<br \/>\nlos gusanos y la pulpa.<br \/>\n(Si alguien mordiera<br \/>\nla guayaba<br \/>\nno sabr\u00eda diferenciar<br \/>\nla suavidad de ninguno.)<\/p>\n<p>Su oficio es estar all\u00ed,<br \/>\nalta y confiada,<br \/>\ndejarse perforar por alg\u00fan pico,<br \/>\nablandarse antes de caer.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>EL PUENTE<\/strong><\/p>\n<p>En ambos extremos del puente<br \/>\nlos remaches petrificados<br \/>\ninmovilizan las cuerdas.<\/p>\n<p>Los paseantes no pierden el tiempo<br \/>\nen detallar los cambios que los a\u00f1os<br \/>\nhan marcado en la estructura.<\/p>\n<p>Es el mismo puente: no es necesario mayor<br \/>\nesfuerzo para nombrarlo de nuevo.<br \/>\nFundado hace cincuenta a\u00f1os,<br \/>\npor personas que probablemente ya han muerto,<br \/>\nmantiene la utilidad de siempre:<br \/>\ndebajo, el mismo r\u00edo sin filosof\u00eda,<br \/>\nni\u00f1os que juegan a ahogarse,<br \/>\ndos muchachos que se tocan escondidos<br \/>\nen la leve corriente para disimular el roce.<\/p>\n<p>Los paseantes van de punta a punta con la<br \/>\nnaturalidad acostumbrada.<br \/>\nNo hay un asombro que les indique<br \/>\nuna nueva interpretaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CARTOGRAF\u00cdA<\/strong><\/p>\n<p>El mar le dio una mordida<br \/>\na la cartograf\u00eda de mi pa\u00eds.<br \/>\nDej\u00f3 bordes<br \/>\ndesiguales en la tierra, dej\u00f3<br \/>\nciudades con forma de sombrero,<br \/>\ncostas hechas con trazo nervioso y estr\u00edas.<\/p>\n<p>El agua de la orilla siempre<br \/>\nes noble con los ni\u00f1os,<br \/>\nes un mar distinto,<br \/>\nsin aguas violentas.<\/p>\n<p>El sol justo encima,<br \/>\ny lo oculto con el pulgar.<br \/>\nLo parto.<br \/>\nAhora tengo dos soles para compartir.<br \/>\nEl sol es riguroso:<br \/>\na esta hora<br \/>\nimporta m\u00e1s el sudor que los abrazos.<\/p>\n<p>Cielo despejado, el cuerpo boca arriba,<br \/>\ntoda la arena metida en el pantal\u00f3n.<br \/>\nLas olas agitan barcos<br \/>\ncon banderas que no reconozco.<br \/>\nTanta gente que pasa,<br \/>\nbuscando m\u00e1s bronce en sus pieles,<br \/>\nun color met\u00e1lico para tapar la palidez<br \/>\ny hacerla menos extranjera.<br \/>\nSolo tengo una mirada sencilla, miedosa,<br \/>\npara este paisaje,<br \/>\ny la sensaci\u00f3n de un vidrio que me separa,<br \/>\nuna tela, una malla, no s\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SEXTINA<\/strong><\/p>\n<p>Nuestro \u00fanico pa\u00eds es esta tabla<br \/>\nr\u00fastica para sostener el pecho.<br \/>\nNo debemos abandonar el monte<br \/>\nde la ni\u00f1ez, diseminar el centro,<br \/>\nborrarlo o anularlo con los dedos,<br \/>\nfundar un territorio con las u\u00f1as.<\/p>\n<p>He mordido suficiente las u\u00f1as<br \/>\nen un acto de fe sobre mi tabla.<br \/>\nQuiz\u00e1 para saber que tengo dedos<br \/>\nsemejantes a mi padre y su pecho.<br \/>\nNo pretendo distanciarme del centro,<br \/>\nde nuestra peque\u00f1a regi\u00f3n, del monte.<\/p>\n<p>Me cans\u00e9 de pisar el mismo monte,<br \/>\namarlo, odiarlo, sobarlo: mis u\u00f1as<br \/>\nvan m\u00e1s all\u00e1 del predecible centro.<br \/>\nNo s\u00e9, a lo mejor buscan otra tabla<br \/>\nque festeje, con nuevo tacto, el pecho.<br \/>\nPor eso ofrezco la arena en mis dedos.<\/p>\n<p>Que se acabe el l\u00edmite de los dedos<br \/>\no que muera de lejos este monte.<br \/>\nAs\u00ed ser\u00e1 m\u00e1s placentero el pecho,<br \/>\nsiempre d\u00f3cil al tacto y a las u\u00f1as.<br \/>\nLo descubro: aunque me arrime y mi tabla<br \/>\nsea mansa, siempre ocultas tu centro.<\/p>\n<p>Lo que amo y admiro tiene su centro<br \/>\nen otra rep\u00fablica, en otros dedos,<br \/>\nen una isla noble, con una tabla<br \/>\n\u00e1spera en la que escribo un nuevo monte:<br \/>\nes mujer de manos humildes y u\u00f1as<br \/>\nque me sostienen firmes en su pecho.<\/p>\n<p>Volver\u00eda a la tibieza del pecho<br \/>\nmaterno (beber su leche del centro<br \/>\nm\u00e1s hermoso); libre, sobrio, sin u\u00f1as,<br \/>\nvolver\u00eda a dividir con los dedos.<br \/>\nDerrotado no partir\u00e9 del monte:<br \/>\nMi herencia, mi pa\u00eds, ser\u00e1 esta tabla.<\/p>\n<p>Quien robe la tabla ver\u00e1 mi pecho,<br \/>\ny nacer\u00e1 un monte m\u00e1s verde, centro<br \/>\nde mi amor; tendr\u00e1 dedos y otras u\u00f1as.<\/p>\n<p style=\"text-align: right;\">&#8220;Pescado,&#8221; &#8220;Andamios,&#8221; &#8220;Descomposici\u00f3n&#8221; y &#8220;El puente&#8221; de\u00a0<em>Andamios<\/em>\u00a0(Editorial Equinoccio, Caracas, Venezuela, 2012)<\/p>\n<p style=\"text-align: right;\">&#8220;Cartograf\u00eda&#8221; y &#8220;Sextina&#8221; de\u00a0<em>Pasajero\u00a0<\/em>(Dcir Ediciones, Caracas, Venezuela, 2015)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detr\u00e1s de la cabeza y los ojos \/ a\u00fan queda un poco de carne. \/\/ Si tuvieras tiempo suficiente \/ entre cada bocado \/ har\u00edas un conteo de las espinas, \/ de las escamas que olvidaste desencajar.<\/p>\n","protected":false},"author":3,"featured_media":2335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5734],"tags":[4458,3],"genre":[2010],"pretext":[],"section":[2345],"translator":[2458],"lal_author":[3489],"class_list":["post-2338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-numero-7","tag-venezuela","genre-poetry-es","section-poetry-es","translator-arthur-malcolm-dixon-es","lal_author-nestor-mendoza-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts\/2338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/comments?post=2338"}],"version-history":[{"count":0,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/posts\/2338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/media?parent=2338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/categories?post=2338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/tags?post=2338"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/genre?post=2338"},{"taxonomy":"pretext","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/pretext?post=2338"},{"taxonomy":"section","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/section?post=2338"},{"taxonomy":"translator","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/translator?post=2338"},{"taxonomy":"lal_author","embeddable":true,"href":"https:\/\/latinamericanliteraturetoday.org\/es\/wp-json\/wp\/v2\/lal_author?post=2338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}